














{"id":140394,"date":"2023-09-01T17:35:57","date_gmt":"2023-09-01T10:35:57","guid":{"rendered":"https:\/\/www.chiangmaiarea1.go.th\/2020\/?p=140394"},"modified":"2023-09-01T17:37:06","modified_gmt":"2023-09-01T10:37:06","slug":"%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1-35","status":"publish","type":"post","link":"https:\/\/www.chiangmaiarea1.go.th\/2020\/%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1-35\/","title":{"rendered":"\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07 (PA) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140395\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1024x577.jpg\" alt=\"\" class=\"wp-image-140395\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e19\u0e32\u0e07\u0e24\u0e17\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e0a\u0e32\u0e0d\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e22\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 \u0e44\u0e17\u0e22\u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07 (PA) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2566 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2566 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e0a\u0e31\u0e49\u0e19 4 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140403\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-1024x577.jpg\" alt=\"\" class=\"wp-image-140403\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13523-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140404\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-1024x577.jpg\" alt=\"\" class=\"wp-image-140404\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13531-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140402\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-1024x577.jpg\" alt=\"\" class=\"wp-image-140402\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13566-1-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140401\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-1024x577.jpg\" alt=\"\" class=\"wp-image-140401\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13578-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140396\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-1024x577.jpg\" alt=\"\" class=\"wp-image-140396\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13580-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140398\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-1024x577.jpg\" alt=\"\" class=\"wp-image-140398\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13598-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140400\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-1024x577.jpg\" alt=\"\" class=\"wp-image-140400\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13611-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140399\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-1024x577.jpg\" alt=\"\" class=\"wp-image-140399\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13612-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140397\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-1024x577.jpg\" alt=\"\" class=\"wp-image-140397\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13613-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"140405\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-1024x577.jpg\" alt=\"\" class=\"wp-image-140405\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2023\/09\/PCM13618-2048x1154.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-140394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activityarea1"],"_links":{"self":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/140394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/comments?post=140394"}],"version-history":[{"count":1,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/140394\/revisions"}],"predecessor-version":[{"id":140406,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/140394\/revisions\/140406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media\/140395"}],"wp:attachment":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media?parent=140394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/categories?post=140394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/tags?post=140394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}