














{"id":143742,"date":"2024-04-26T15:59:54","date_gmt":"2024-04-26T08:59:54","guid":{"rendered":"https:\/\/www.chiangmaiarea1.go.th\/2020\/?p=143742"},"modified":"2024-04-26T16:01:37","modified_gmt":"2024-04-26T09:01:37","slug":"%e0%b8%a3%e0%b8%a1%e0%b8%a7-%e0%b8%a8%e0%b8%98-%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a5%e0%b8%87%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%95","status":"publish","type":"post","link":"https:\/\/www.chiangmaiarea1.go.th\/2020\/%e0%b8%a3%e0%b8%a1%e0%b8%a7-%e0%b8%a8%e0%b8%98-%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a5%e0%b8%87%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%95\/","title":{"rendered":"(\u0e23\u0e21\u0e27.\u0e28\u0e18.) \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143743\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143743\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e1e\u0e25\u0e15\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 (\u0e23\u0e21\u0e27.\u0e28\u0e18.) \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e14\u0e2d\u0e19\u0e0a\u0e31\u0e22 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e32\u0e07\u0e14\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e42\u0e14\u0e22\u0e21\u0e35 \u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e23\u0e49\u0e2d\u0e22\u0e15\u0e23\u0e35 \u0e18\u0e19\u0e38 \u0e27\u0e07\u0e29\u0e4c\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 (\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e1e\u0e10.) \u0e14\u0e23.\u0e40\u0e01\u0e28\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e28\u0e38\u0e20\u0e27\u0e32\u0e19\u0e34\u0e0a <a><\/a>\u0e23\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e1e\u0e10. \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 \u0e1e\u0e25\u0e15\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u201c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e14\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u201d \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e44\u0e17\u0e22\u0e17\u0e38\u0e01\u0e04\u0e19<\/p>\n\n\n\n<p>\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e19\u0e32\u0e22\u0e27\u0e31\u0e0a\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e4c \u0e40\u0e17\u0e1e\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143746\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439839765_963046472278210_6423281212704324441_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143746\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439839765_963046472278210_6423281212704324441_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439839765_963046472278210_6423281212704324441_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439839765_963046472278210_6423281212704324441_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439839765_963046472278210_6423281212704324441_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"143750\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439402498_963046462278211_615993549648453431_n-1024x577.jpg\" alt=\"\" class=\"wp-image-143750\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439402498_963046462278211_615993549648453431_n-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439402498_963046462278211_615993549648453431_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439402498_963046462278211_615993549648453431_n-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439402498_963046462278211_615993549648453431_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"143749\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439212987_963046248944899_2725080133194860388_n-1024x577.jpg\" alt=\"\" class=\"wp-image-143749\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439212987_963046248944899_2725080133194860388_n-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439212987_963046248944899_2725080133194860388_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439212987_963046248944899_2725080133194860388_n-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439212987_963046248944899_2725080133194860388_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143751\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439488296_963046195611571_5284204103703153006_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143751\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439488296_963046195611571_5284204103703153006_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439488296_963046195611571_5284204103703153006_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439488296_963046195611571_5284204103703153006_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439488296_963046195611571_5284204103703153006_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143753\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439581334_963046262278231_6455128103521709748_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143753\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439581334_963046262278231_6455128103521709748_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439581334_963046262278231_6455128103521709748_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439581334_963046262278231_6455128103521709748_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439581334_963046262278231_6455128103521709748_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143748\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1-1024x576.jpg\" alt=\"\" class=\"wp-image-143748\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439599182_963046345611556_3427803625149591612_n-1.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" data-id=\"143744\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439258978_963046175611573_3392312037202678280_n-1024x578.jpg\" alt=\"\" class=\"wp-image-143744\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439258978_963046175611573_3392312037202678280_n-1024x578.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439258978_963046175611573_3392312037202678280_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439258978_963046175611573_3392312037202678280_n-768x433.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439258978_963046175611573_3392312037202678280_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" data-id=\"143745\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439312989_963046365611554_7411281068730558220_n-1024x594.jpg\" alt=\"\" class=\"wp-image-143745\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439312989_963046365611554_7411281068730558220_n-1024x594.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439312989_963046365611554_7411281068730558220_n-300x174.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439312989_963046365611554_7411281068730558220_n-768x445.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439312989_963046365611554_7411281068730558220_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143752\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439598626_963046252278232_8561388248373471765_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143752\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439598626_963046252278232_8561388248373471765_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439598626_963046252278232_8561388248373471765_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439598626_963046252278232_8561388248373471765_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439598626_963046252278232_8561388248373471765_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"143747\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439442574_963046208944903_4588454787140847583_n-1024x576.jpg\" alt=\"\" class=\"wp-image-143747\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439442574_963046208944903_4588454787140847583_n-1024x576.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439442574_963046208944903_4588454787140847583_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439442574_963046208944903_4588454787140847583_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/04\/439442574_963046208944903_4588454787140847583_n.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e1e\u0e25\u0e15\u0e33\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e01\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":143744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-143742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activityarea1"],"_links":{"self":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/143742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/comments?post=143742"}],"version-history":[{"count":3,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/143742\/revisions"}],"predecessor-version":[{"id":143756,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/143742\/revisions\/143756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media\/143744"}],"wp:attachment":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media?parent=143742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/categories?post=143742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/tags?post=143742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}