














{"id":145387,"date":"2024-06-08T15:23:43","date_gmt":"2024-06-08T08:23:43","guid":{"rendered":"https:\/\/www.chiangmaiarea1.go.th\/2020\/?p=145387"},"modified":"2024-06-08T15:23:44","modified_gmt":"2024-06-08T08:23:44","slug":"%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%94%e0%b8%b3%e0%b9%80%e0%b8%99%e0%b8%b4%e0%b8%99-12","status":"publish","type":"post","link":"https:\/\/www.chiangmaiarea1.go.th\/2020\/%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%94%e0%b8%b3%e0%b9%80%e0%b8%99%e0%b8%b4%e0%b8%99-12\/","title":{"rendered":"\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e35 \u0e1e.\u0e28.2567"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145388\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145388\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448076150_990959959486861_8022122767686898856_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e35 \u0e1e.\u0e28.2567 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e04 \u0e01 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04 \u0e02 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u2013 9 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2567<\/p>\n\n\n\n<p>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e19\u0e32\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e21\u0e39\u0e25\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19 \u0e2d.\u0e01.\u0e04.\u0e28.\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e01\u0e29\u0e34\u0e14\u0e34\u0e28 \u0e2a\u0e25\u0e48\u0e32\u0e1b\u0e31\u0e19 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19 \u0e2d.\u0e01.\u0e04.\u0e28. \u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e23\u0e31\u0e0a\u0e0e\u0e32 \u0e19\u0e32\u0e07\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e0a\u0e32\u0e0d\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e23\u0e48\u0e27\u0e21\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e21\u0e35\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e2d\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19 306 \u0e04\u0e19 \u0e21\u0e32\u0e2a\u0e2d\u0e1a 291 \u0e04\u0e19 \u0e02\u0e32\u0e14\u0e2a\u0e2d\u0e1a 15 \u0e04\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145390\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145390\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447998306_990960202820170_5588612372039064550_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145396\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145396\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116504_990960122820178_2259845265754223570_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145395\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145395\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448027180_990960146153509_6640756814397447800_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145391\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145391\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447970924_990959982820192_9099019264386399196_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145394\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145394\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447997612_990960109486846_381901261928409333_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145393\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145393\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969307_990960006153523_6743898061650784852_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145392\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145392\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448002797_990959946153529_4686372387519104444_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145389\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145389\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/447969254_990959939486863_1929694140170336203_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e14\u0e33\u0e40 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":145388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-145387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activityarea1"],"_links":{"self":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/comments?post=145387"}],"version-history":[{"count":1,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145387\/revisions"}],"predecessor-version":[{"id":145397,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145387\/revisions\/145397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media\/145388"}],"wp:attachment":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media?parent=145387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/categories?post=145387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/tags?post=145387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}