














{"id":145421,"date":"2024-06-09T17:39:58","date_gmt":"2024-06-09T10:39:58","guid":{"rendered":"https:\/\/www.chiangmaiarea1.go.th\/2020\/?p=145421"},"modified":"2024-06-09T17:39:59","modified_gmt":"2024-06-09T10:39:59","slug":"%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2-18","status":"publish","type":"post","link":"https:\/\/www.chiangmaiarea1.go.th\/2020\/%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2-18\/","title":{"rendered":"\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e35 \u0e1e.\u0e28.2567 \u0e20\u0e32\u0e04 \u0e02"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145422\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145422\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448154709_991581702758020_3163661772713877434_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2567 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 (\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1) \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e19\u0e32\u0e22\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e23\u0e31\u0e0a\u0e0e\u0e32 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e1b\u0e35 \u0e1e.\u0e28.2567 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e20\u0e32\u0e04 \u0e02 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e01\u0e33\u0e01\u0e31\u0e1a \u0e14\u0e39\u0e41\u0e25 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 \u0e01.\u0e04.\u0e28.\u0e41\u0e25\u0e30 \u0e2a\u0e1e\u0e10.\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e2d\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19 306 \u0e04\u0e19 \u0e21\u0e32\u0e2a\u0e2d\u0e1a 291 \u0e04\u0e19 \u0e02\u0e32\u0e14\u0e2a\u0e2d\u0e1a 15 \u0e04\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145425\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145425\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581846091339_6743305882902454317_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145424\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145424\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448023989_991581726091351_3646491628635606289_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145426\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145426\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448030202_991581742758016_8830758582253624853_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145427\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145427\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448150477_991581462758044_476580941932125734_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145428\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145428\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116502_991581516091372_6368635303542236205_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"145423\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n-1024x683.jpg\" alt=\"\" class=\"wp-image-145423\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/06\/448116118_991581492758041_4469870881694076126_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2567 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":145422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-145421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activityarea1"],"_links":{"self":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/comments?post=145421"}],"version-history":[{"count":1,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145421\/revisions"}],"predecessor-version":[{"id":145429,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/145421\/revisions\/145429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media\/145422"}],"wp:attachment":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media?parent=145421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/categories?post=145421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/tags?post=145421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}