














{"id":146281,"date":"2024-07-01T15:51:03","date_gmt":"2024-07-01T08:51:03","guid":{"rendered":"https:\/\/www.chiangmaiarea1.go.th\/2020\/?p=146281"},"modified":"2024-07-02T15:52:10","modified_gmt":"2024-07-02T08:52:10","slug":"%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%9b%e0%b8%90%e0%b8%a1%e0%b8%99-3","status":"publish","type":"post","link":"https:\/\/www.chiangmaiarea1.go.th\/2020\/%e0%b8%9c%e0%b8%ad-%e0%b8%aa%e0%b8%9e%e0%b8%9b-%e0%b9%80%e0%b8%8a%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%82%e0%b8%95-1-%e0%b8%9b%e0%b8%90%e0%b8%a1%e0%b8%99-3\/","title":{"rendered":"\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e27\u0e32\u0e17\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"146282\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n-1024x683.jpg\" alt=\"\" class=\"wp-image-146282\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449685401_1005814618001395_6696542290422458734_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 (\u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e27\u0e32\u0e17\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e1a\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19 6 \u0e23\u0e32\u0e22 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e19\u0e32\u0e22\u0e27\u0e31\u0e25\u0e25\u0e20 \u0e20\u0e39\u0e08\u0e2d\u0e21\u0e08\u0e34\u0e15\u0e23 \u0e23\u0e2d\u0e07 \u0e1c\u0e2d.\u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1 \u0e19\u0e32\u0e22\u0e2d\u0e38\u0e17\u0e31\u0e22 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e42\u0e01\u0e0d \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e35 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e1c\u0e2d.\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39 \u0e01\u0e0f \u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e34\u0e01\u0e08\u0e48\u0e32\u0e22\u0e15\u0e23\u0e07\u0e04\u0e48\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e2a\u0e1e\u0e1b.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e02\u0e15 1<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"146284\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n-1024x683.jpg\" alt=\"\" class=\"wp-image-146284\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449694664_1005814508001406_8140068434349827227_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"146285\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n-1024x683.jpg\" alt=\"\" class=\"wp-image-146285\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n-1536x1025.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705561_1005814578001399_8222401669584781922_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"146283\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n-1024x683.jpg\" alt=\"\" class=\"wp-image-146283\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n-1536x1024.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449705233_1005814488001408_886506099401699855_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"146287\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n-1024x577.jpg\" alt=\"\" class=\"wp-image-146287\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n-1024x577.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n-300x169.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n-768x432.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n-1536x865.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449531301_1005814561334734_5853307689721979547_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"146286\" src=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n-1024x683.jpg\" alt=\"\" class=\"wp-image-146286\" srcset=\"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n-1024x683.jpg 1024w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n-300x200.jpg 300w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n-768x512.jpg 768w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n-1536x1025.jpg 1536w, https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-content\/uploads\/2024\/07\/449699139_1005814534668070_2561943248184582433_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e28\u0e23\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":146282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-146281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activityarea1"],"_links":{"self":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/146281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/comments?post=146281"}],"version-history":[{"count":1,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/146281\/revisions"}],"predecessor-version":[{"id":146288,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/posts\/146281\/revisions\/146288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media\/146282"}],"wp:attachment":[{"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/media?parent=146281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/categories?post=146281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiangmaiarea1.go.th\/2020\/wp-json\/wp\/v2\/tags?post=146281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}